{"id":279,"date":"2022-08-26T15:22:45","date_gmt":"2022-08-26T09:52:45","guid":{"rendered":"https:\/\/www.ahlehadees.org\/urdu\/?p=279"},"modified":"2022-08-26T15:22:45","modified_gmt":"2022-08-26T09:52:45","slug":"islahe-samaj-august-2022","status":"publish","type":"post","link":"https:\/\/www.ahlehadees.org\/urdu\/islahe-samaj-august-2022\/","title":{"rendered":"Islahe Samaj, August 2022"},"content":{"rendered":"<p><a href=\"https:\/\/www.ahlehadees.org\/urdu\/wp-content\/uploads\/sites\/5\/2022\/08\/August-2022-F.pdf\">August-2022-F<\/a>\u00a0<a href=\"https:\/\/www.ahlehadees.org\/urdu\/wp-content\/uploads\/sites\/5\/2022\/08\/August-2022-F.pdf\"><strong>Download<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>August-2022-F\u00a0Download<\/p>\n","protected":false},"author":2,"featured_media":281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11"],"_links":{"self":[{"href":"https:\/\/www.ahlehadees.org\/urdu\/wp-json\/wp\/v2\/posts\/279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ahlehadees.org\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ahlehadees.org\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ahlehadees.org\/urdu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ahlehadees.org\/urdu\/wp-json\/wp\/v2\/comments?post=279"}],"version-history":[{"count":1,"href":"https:\/\/www.ahlehadees.org\/urdu\/wp-json\/wp\/v2\/posts\/279\/revisions"}],"predecessor-version":[{"id":282,"href":"https:\/\/www.ahlehadees.org\/urdu\/wp-json\/wp\/v2\/posts\/279\/revisions\/282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ahlehadees.org\/urdu\/wp-json\/wp\/v2\/media\/281"}],"wp:attachment":[{"href":"https:\/\/www.ahlehadees.org\/urdu\/wp-json\/wp\/v2\/media?parent=279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ahlehadees.org\/urdu\/wp-json\/wp\/v2\/categories?post=279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ahlehadees.org\/urdu\/wp-json\/wp\/v2\/tags?post=279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}